{"id":3064,"date":"2023-06-12T07:28:49","date_gmt":"2023-06-12T07:28:49","guid":{"rendered":"https:\/\/rpdetectives.com\/proves-quin-valor-tenen-en-un-judici\/"},"modified":"2023-06-12T07:28:49","modified_gmt":"2023-06-12T07:28:49","slug":"proves-quin-valor-tenen-en-un-judici","status":"publish","type":"post","link":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/","title":{"rendered":"Proves: Quin valor tenen en un judici"},"content":{"rendered":"<div class=\"elementor-element elementor-element-7901c70 elementor-widget elementor-widget-text-editor\" data-id=\"7901c70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>A continuaci\u00f3 aclarirem quin valor tenen les proves en un judici i com assegurar-nos que aquestes siguin \u00fatils per a aquesta inst\u00e0ncia (judici).<\/p>\n<h3><strong> EN QUIN TIPUS D&#8217;INVESTIGACIONS S\u00d3N \u00daTILS ELS DETECTIVES PRIVATS?<\/strong><\/h3>\n<p>Recordem que els detectius privats s\u00f3n professionals que han de passar per una formaci\u00f3 espec\u00edfica per poder exercir la seva professi\u00f3. A m\u00e9s, han de seguir un marc legal for\u00e7a estricte per realitzar les investigacions privades. Aix\u00f2 implica que aquestes investigacions comptessin amb certs l\u00edmits en la forma de l&#8217;obtenci\u00f3 de proves, a m\u00e9s de delimitar els casos en qu\u00e8 poden actuar. Un investigador privat habilitat ser\u00e0 \u00fatil per abastar un rang ampli de recerca.<\/p>\n<p>Les proves d&#8217;un professional privat poden ser de for\u00e7a utilitat per als advocats, ja que les investigacions privades s\u00f3n objectives, per la qual cosa s&#8217;obtenen for\u00e7a evid\u00e8ncies a trav\u00e9s de l&#8217;observaci\u00f3 activa, \u00e9s a dir, el treball dels detectius privats. Al costat de l&#8217;informe\/part, tamb\u00e9 es poden adjuntar i presentar proves en formats diferents, com per exemple, imatges i v\u00eddeos que confirmin el que diu aquest informe\/part.<\/p>\n<p>Una de les preguntes m\u00e9s freq\u00fcents en clients d&#8217;un detectiu privat \u00e9s si poden proporcionar proves per presentar-les davant d&#8217;un jutge, la resposta \u00e9s SI, S\u00cd PODEN, sempre que compleixin les condicions que la Llei estipula.<\/p>\n<h3><strong>INFORME COM A MITJ\u00c0 DE PROVA<\/strong><\/h3>\n<p>Recordem que quan s&#8217;estableix finalitza una investigaci\u00f3 privada, com a resultat, el detectiu haur\u00e0 de redactar un informe per poder-lo presentar al seu client. Aquest document \u00e9s el que es pot presentar davant d&#8217;un jutge, ja que \u00e9s un dels mitjans de prova que es permeten durant un proc\u00e9s judicial, segons dicta la Llei d&#8217;Enjudiciament Civil.<\/p>\n<p>Es podria dir, que l&#8217;informe \u00e9s el testimoni del detectiu privat sobre els fets ocorreguts en un passat, del qual ha estat testimoni. S&#8217;hi relata el que s&#8217;ha vist i escoltat durant la investigaci\u00f3 amb una ordre seq\u00fcencial. Tamb\u00e9 \u00e9s important que en aquest informe es plasmin qui o qui ha participat durant la investigaci\u00f3 privada. Els fets que es descriguin durant l&#8217;informe es podran donar suport amb altres fitxers, com per exemple; fotografies, v\u00eddeos i m\u00e9s proves que obtingui el detectiu privat durant la investigaci\u00f3.<\/p>\n<p>Recordar que perqu\u00e8 un informe\/parteix sigui adm\u00e8s com a prova, haur\u00e0 de complir unes certes condicions. Algunes d&#8217;aquestes condicions s\u00f3n:<\/p>\n<p>-L&#8217;informe haur\u00e0 d&#8217;estar elaborat per un professional habilitat, \u00e9s a dir, aquest s&#8217;ha de trobar en possessi\u00f3 de la targeta d&#8217;identificaci\u00f3 professional (TIP), que atorga la direcci\u00f3 general de la policia.<\/p>\n<p>Si aquest detectiu privat no est\u00e0 habilitat per exercir com a tal, es considera intrusisme laboral, i les proves aportades no tenen cap valor davant un jutge.<\/p>\n<p>-A l&#8217;informe hauran d&#8217;apar\u00e8ixer tots els noms de totes les persones que han participat en la investigaci\u00f3. Tamb\u00e9 s&#8217;hauran d&#8217;expressar els m\u00e8todes que s&#8217;han fet servir per obtenir aix\u00ed les proves, aquests \u00faltims no hauran de vulnerar els drets fonamentals de les persones investigades.<\/p>\n<p>Si l&#8217;objecte de la investigaci\u00f3 privada s\u00f3n les estafes a internet, haur\u00e0 d&#8217;acudir un p\u00e8rit inform\u00e0tic a declarar davant un jutge durant el judici.<\/p>\n<p>-Si la part contr\u00e0ria impugna l&#8217;informe elaborat per un detectiu privat, aquest darrer haur\u00e0 d&#8217;acudir al jutjat a rectificar-lo davant d&#8217;un jutge durant el judici.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-96a5dbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"96a5dbc\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9195b57\" data-id=\"9195b57\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-15e2863 elementor-widget elementor-widget-text-editor\" data-id=\"15e2863\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<h3><strong>VALOR DE PROVES EN JUDIIS<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-6612421 elementor-widget elementor-widget-image\" data-id=\"6612421\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-image\">Despr\u00e9s de fer una investigaci\u00f3 privada, el detectiu oferir\u00e0 un suport litigi, aix\u00f2 vol dir que tot el proc\u00e9s estar\u00e0 dins del marc legal, aix\u00ed com els p\u00e8rits estan preparats professionalment per parlar i declarar davant un jutge, i respondre aix\u00ed totes les preguntes que tinguin una relaci\u00f3 amb linforme redactat pr\u00e8viament.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e27bf5c\" data-id=\"e27bf5c\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-8d5cc29 elementor-widget elementor-widget-text-editor\" data-id=\"8d5cc29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>El Tribunal Suprem considera un detectiu privat com un testimoni privilegiat, quan aquest es presenta davant d&#8217;un proc\u00e9s judicial, ja que aquest \u00faltim \u00e9s un professional privat que ha rebut l&#8217;habilitaci\u00f3 (TIP) per fer investigacions i, a m\u00e9s, les proves que presenti davant un judici estaran recolzades per fets verificables.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d2d9ea0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2d9ea0\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63fc5f3\" data-id=\"63fc5f3\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-bedb1ea elementor-widget elementor-widget-text-editor\" data-id=\"bedb1ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<h3><strong>MARC LEGAL<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-8c015e7 elementor-widget elementor-widget-image\" data-id=\"8c015e7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-image\">Dins del marc jur\u00eddic estan validades la presentaci\u00f3 de proves d&#8217;un detectiu privat davant d&#8217;un judici. A l&#8217;article n\u00famero 265 de la llei d&#8217;Enjudiciament Civil observem com es reconeix l&#8217;informe dels professionals privats com una forma espec\u00edfica i diferent de prova testifical. En aquesta Llei per\u00f2 a l&#8217;article n\u00famero 380.0 cita textualment que el reconeixement de l&#8217;informe pericial en aquests mateixos, quan continguin conclusions i observacions basades en coneixements t\u00e8cnics, art\u00edstics o pr\u00e0ctics.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e54542a\" data-id=\"e54542a\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-d536cc8 elementor-widget elementor-widget-text-editor\" data-id=\"d536cc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Aquesta Llei tamb\u00e9 indica i descriu com haur\u00e0 de ser un interrogatori cap a un detectiu privat durant la ratificaci\u00f3 de l&#8217;informe redactat anteriorment pel mateix. Totes les preguntes s&#8217;han de referir als fets que es relaten en aquest informe. El professional privat es presenciar\u00e0 davant d&#8217;un jutge nom\u00e9s per parlar dels fets que va veure o que escolto durant la investigaci\u00f3, i que tamb\u00e9 es troben reflectits a l&#8217;informe. Aquest ser\u00e0 imparcial, igual que l&#8217;informe, aix\u00f2 \u00e9s el que marca la difer\u00e8ncia davant de la resta de testimonis.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8cfa7ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cfa7ac\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0e1b4a1\" data-id=\"0e1b4a1\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-29e319d elementor-widget elementor-widget-text-editor\" data-id=\"29e319d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<h3><strong>PROVES NO V\u00c0LIDES<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-2319163 elementor-widget elementor-widget-image\" data-id=\"2319163\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-image\">Com altres professions, els detectius privats s&#8217;han d&#8217;ajustar al que els permet la Llei, ja que hi ha l\u00edmits que aquests han de respectar i que si no ho fan, poden rebre una sanci\u00f3 o caure en un delicte.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f7634ce\" data-id=\"f7634ce\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-2617d62 elementor-widget elementor-widget-text-editor\" data-id=\"2617d62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>A continuaci\u00f3 explicarem que tres condicions b\u00e0siques s\u00f3n necess\u00e0ries per no posar en risc la validesa de les proves d&#8217;un detectiu privat davant d&#8217;un judici:<\/p>\n<ul>\n<li>El detectiu privat haur\u00e0 d&#8217;estar habilitat.<\/li>\n<li>La persona que contracta un professional privat haur\u00e0 de tenir un inter\u00e8s leg\u00edtim perqu\u00e8 s&#8217;inici\u00ef la investigaci\u00f3.<\/li>\n<li>En cap moment, durant la investigaci\u00f3 no es podr\u00e0 vulnerar els drets fonamentals dels involucrats en aquesta.<\/li>\n<\/ul>\n<p>Recordem que perqu\u00e8 un detectiu privat estigui habilitat, aquest ha de posseir el TIP, aquesta acreditaci\u00f3 indica que aquest \u00e9s un professional i que disposa de la formaci\u00f3 adequada per fer investigacions.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3 aclarirem quin valor tenen les proves en un judici i com assegurar-nos que aquestes siguin \u00fatils per a aquesta inst\u00e0ncia (judici). EN QUIN TIPUS D&#8217;INVESTIGACIONS S\u00d3N \u00daTILS ELS DETECTIVES PRIVATS? Recordem que els detectius privats s\u00f3n professionals que han de passar per una formaci\u00f3 espec\u00edfica per poder exercir la seva professi\u00f3. A m\u00e9s, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proves: Quin valor tenen en un judici - RP Detectives Privados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proves: Quin valor tenen en un judici - RP Detectives Privados\" \/>\n<meta property=\"og:description\" content=\"A continuaci\u00f3 aclarirem quin valor tenen les proves en un judici i com assegurar-nos que aquestes siguin \u00fatils per a aquesta inst\u00e0ncia (judici). EN QUIN TIPUS D&#8217;INVESTIGACIONS S\u00d3N \u00daTILS ELS DETECTIVES PRIVATS? Recordem que els detectius privats s\u00f3n professionals que han de passar per una formaci\u00f3 espec\u00edfica per poder exercir la seva professi\u00f3. A m\u00e9s, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/\" \/>\n<meta property=\"og:site_name\" content=\"RP Detectives Privados\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T07:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"559\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/#\\\/schema\\\/person\\\/bf3c462170af3c967f01976eb192741c\"},\"headline\":\"Proves: Quin valor tenen en un judici\",\"datePublished\":\"2023-06-12T07:28:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/\"},\"wordCount\":1047,\"image\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rpdetectives.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pruebas.jpg\",\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/\",\"url\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/\",\"name\":\"Proves: Quin valor tenen en un judici - RP Detectives Privados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rpdetectives.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pruebas.jpg\",\"datePublished\":\"2023-06-12T07:28:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/#\\\/schema\\\/person\\\/bf3c462170af3c967f01976eb192741c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rpdetectives.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pruebas.jpg\",\"contentUrl\":\"https:\\\/\\\/rpdetectives.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/pruebas.jpg\",\"width\":840,\"height\":559},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/proves-quin-valor-tenen-en-un-judici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/inici\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proves: Quin valor tenen en un judici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/\",\"name\":\"RP Detectives Privados\",\"description\":\"Gabinete de investigaci\u00f3n privada, fue fundado en el a\u00f1o 1989, por los hermanos Roger y Pau FERRER CABRE.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/#\\\/schema\\\/person\\\/bf3c462170af3c967f01976eb192741c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/rpdetectives.com\"],\"url\":\"https:\\\/\\\/rpdetectives.com\\\/ca\\\/author\\\/useradmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proves: Quin valor tenen en un judici - RP Detectives Privados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/","og_locale":"ca_ES","og_type":"article","og_title":"Proves: Quin valor tenen en un judici - RP Detectives Privados","og_description":"A continuaci\u00f3 aclarirem quin valor tenen les proves en un judici i com assegurar-nos que aquestes siguin \u00fatils per a aquesta inst\u00e0ncia (judici). EN QUIN TIPUS D&#8217;INVESTIGACIONS S\u00d3N \u00daTILS ELS DETECTIVES PRIVATS? Recordem que els detectius privats s\u00f3n professionals que han de passar per una formaci\u00f3 espec\u00edfica per poder exercir la seva professi\u00f3. A m\u00e9s, [&hellip;]","og_url":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/","og_site_name":"RP Detectives Privados","article_published_time":"2023-06-12T07:28:49+00:00","og_image":[{"width":840,"height":559,"url":"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#article","isPartOf":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/"},"author":{"name":"admin","@id":"https:\/\/rpdetectives.com\/ca\/#\/schema\/person\/bf3c462170af3c967f01976eb192741c"},"headline":"Proves: Quin valor tenen en un judici","datePublished":"2023-06-12T07:28:49+00:00","mainEntityOfPage":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/"},"wordCount":1047,"image":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#primaryimage"},"thumbnailUrl":"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg","articleSection":["Uncategorized @ca"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/","url":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/","name":"Proves: Quin valor tenen en un judici - RP Detectives Privados","isPartOf":{"@id":"https:\/\/rpdetectives.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#primaryimage"},"image":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#primaryimage"},"thumbnailUrl":"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg","datePublished":"2023-06-12T07:28:49+00:00","author":{"@id":"https:\/\/rpdetectives.com\/ca\/#\/schema\/person\/bf3c462170af3c967f01976eb192741c"},"breadcrumb":{"@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#primaryimage","url":"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg","contentUrl":"https:\/\/rpdetectives.com\/wp-content\/uploads\/2023\/06\/pruebas.jpg","width":840,"height":559},{"@type":"BreadcrumbList","@id":"https:\/\/rpdetectives.com\/ca\/proves-quin-valor-tenen-en-un-judici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rpdetectives.com\/ca\/inici\/"},{"@type":"ListItem","position":2,"name":"Proves: Quin valor tenen en un judici"}]},{"@type":"WebSite","@id":"https:\/\/rpdetectives.com\/ca\/#website","url":"https:\/\/rpdetectives.com\/ca\/","name":"RP Detectives Privados","description":"Gabinete de investigaci\u00f3n privada, fue fundado en el a\u00f1o 1989, por los hermanos Roger y Pau FERRER CABRE.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpdetectives.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/rpdetectives.com\/ca\/#\/schema\/person\/bf3c462170af3c967f01976eb192741c","name":"admin","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/74a72230a5d1db38752dcb41f399c7c16604457b70623f49f8f546bd670ce226?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/rpdetectives.com"],"url":"https:\/\/rpdetectives.com\/ca\/author\/useradmin\/"}]}},"_links":{"self":[{"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/posts\/3064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/comments?post=3064"}],"version-history":[{"count":0,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/posts\/3064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/media\/674"}],"wp:attachment":[{"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/media?parent=3064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/categories?post=3064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpdetectives.com\/ca\/wp-json\/wp\/v2\/tags?post=3064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}